{"id":53307,"date":"2023-12-14T19:10:09","date_gmt":"2023-12-14T19:10:09","guid":{"rendered":"https:\/\/business.ticketmaster.com\/fr\/?p=53307"},"modified":"2024-02-29T21:10:47","modified_gmt":"2024-02-29T21:10:47","slug":"peach-bowl-inc-accueillir-les-plus-grands-matchs-du-football-universitaire-aux-cotes-de-ticketmaster","status":"publish","type":"post","link":"https:\/\/business.ticketmaster.com\/fr\/peach-bowl-inc-accueillir-les-plus-grands-matchs-du-football-universitaire-aux-cotes-de-ticketmaster\/","title":{"rendered":"Peach Bowl, Inc. &#8211; Accueillir les plus grands matchs du football universitaire aux c\u00f4t\u00e9s de Ticketmaster"},"content":{"rendered":"\n<div class=\"wp-block-group is-style-padding-alt has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\">Chaque ann\u00e9e, Peach Bowl, Inc. attire l\u2019attention nationale sur le Mercedes-Benz Stadium d\u2019Atlanta, en G\u00e9orgie, qui accueille certains des plus grands matchs de football universitaire de la saison. Des mois de planification vont dans ces \u00e9v\u00e9nements \u00e0 grande \u00e9chelle pour assurer une exp\u00e9rience transparente pour les fans le jour du match.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mike Gilbert, directeur de la billetterie pour Peach Bowl, Inc., partage des id\u00e9es sur la fa\u00e7on dont les outils, le soutien et les partenariats de Ticketmaster ont contribu\u00e9 \u00e0 propulser le Chick-fil-A Peach Bowl et l\u2019Aflac Kickoff Game vers le succ\u00e8s, \u00e9tablissant Peach Bowl, Inc. comme un h\u00f4te de premier plan pour les matchs de football universitaire sur site neutre.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Un partenariat de longue date enracin\u00e9 dans le succ\u00e8s<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En 2010, Peach Bowl, Inc. a d\u00e9cid\u00e9 de passer \u00e0 Ticketmaster comme fournisseur de billetterie. Le but de cette d\u00e9cision strat\u00e9gique \u00e9tait d\u2019am\u00e9liorer leur gestion et la supervision de l\u2019entonnoir de vente, ainsi que d\u2019am\u00e9liorer l\u2019exp\u00e9rience de billetterie de bout en bout. Gilbert, qui faisait partie du personnel \u00e0 l\u2019\u00e9poque, a soulign\u00e9 l\u2019importance de la d\u00e9cision en termes de personnalisation et de rationalisation des abonnements, des forfaits et des engagements des fans.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;Nous pouvons pousser les si\u00e8ges vers le bas pour les grossistes et faire des renouvellements plus facilement. Cette gestion am\u00e9lior\u00e9e du processus \u00e9tait la raison pour laquelle nous voulions collaborer avec Ticketmaster.&nbsp;\u00bb<\/p>\n<cite>Mike Gilbert, directeur de la billetterie, Peach Bowl, Inc.<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Monter de niveau avec des billets num\u00e9riques<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Peach Bowl, Inc. a \u00e9t\u00e9 impressionn\u00e9 par l\u2019approche moderne et ax\u00e9e sur l\u2019avenir de Ticketmaster en mati\u00e8re de billetterie. Lorsque leur repr\u00e9sentant Ticketmaster a sugg\u00e9r\u00e9 l\u2019adoption de la billetterie num\u00e9rique pour le match de demi-finale des s\u00e9ries \u00e9liminatoires de football coll\u00e9gial en 2019, l\u2019\u00e9quipe de Peach Bowl, Inc. a rapidement accept\u00e9.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avec un d\u00e9lai de deux mois avant le jour du match, le projet a n\u00e9cessit\u00e9 l\u2019aide de tout le monde, et Ticketmaster a fourni des mod\u00e8les et des processus rationalis\u00e9s afin de faciliter une transition en douceur. \u00ab Quand nous sommes arriv\u00e9s le jour du match, il n\u2019y avait pas de probl\u00e8mes&#8230; Nous n\u2019aurions pas pu le faire sans le soutien d\u00e9vou\u00e9 de Ticketmaster \u00bb, a d\u00e9clar\u00e9 Gilbert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gilbert avait \u00e9t\u00e9 t\u00e9moin de la quantit\u00e9 de fraude associ\u00e9e aux billets papier, ce qui a clairement indiqu\u00e9 que le passage au num\u00e9rique \u00e9tait n\u00e9cessaire. La technologie SafeTix de Ticketmaster s\u2019attaque aux billets frauduleux, donnant aux fans la confiance que leurs billets sont s\u00fbrs et authentiques. Gilbert croit qu\u2019en se pr\u00e9sentant devant le passage au num\u00e9rique \u00e0 l\u2019\u00e9chelle de l\u2019industrie, Ticketmaster a contribu\u00e9 \u00e0 solidifier Peach Bowl, Inc. en tant que leader dans l\u2019espace du football universitaire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Soutien permanent \u2014 Tous les jours de l\u2019ann\u00e9e<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Selon Gilbert, le service exceptionnel de Ticketmaster \u00e9limine toute pr\u00e9occupation d\u2019\u00eatre n\u00e9glig\u00e9 comme un \u00e9v\u00e9nement \u00ab&nbsp;unique&nbsp;\u00bb. Le soutien de Ticketmaster s\u2019\u00e9tend au-del\u00e0 des simples solutions de billetterie, avec des sp\u00e9cialistes du soutien client d\u00e9di\u00e9s qui offrent une assistance \u00e0 distance et sur site pour chaque match de Peach Bowl, Inc.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ticketmaster s\u2019efforce de fournir le m\u00eame niveau de soutien \u00e0 tous les clients, quelle que soit la taille ou la port\u00e9e de l\u2019\u00e9v\u00e9nement. Peu importe l\u2019\u00e9v\u00e9nement, Ticketmaster s\u2019assure que tous les clients se sentent entendus et soutenus.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;Je pense que Ticketmaster fait un excellent travail en \u00e9coutant les commentaires de tout le monde et en essayant de cr\u00e9er le meilleur syst\u00e8me possible pour vous. Ils font un excellent travail pour nous faire sentir les bienvenus et faire partie de la famille. Leur \u00e9quipe me traite toujours avec le m\u00eame respect que les clients qui ont plus d\u2019\u00e9v\u00e9nements que nous.&nbsp;\u00bb<\/p>\n<cite>Mike Gilbert, directeur de la billetterie, Peach Bowl, Inc.<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Outils pour un engagement maximal<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Un \u00e9v\u00e9nement \u00e0 grande \u00e9chelle comme le Chick-fil-A Peach Bowl ou l\u2019Aflac Kickoff Game exige \u00e9galement une strat\u00e9gie de marketing par courriel robuste pour stimuler l\u2019engagement aupr\u00e8s des fans ainsi que les ventes. En tant que client Ticketmaster, Peach Bowl, Inc. a acc\u00e8s \u00e0 des outils de pointe tels que TM1 Engagement, une plateforme de marketing par courriel qui offre une segmentation bas\u00e9e sur les \u00e9v\u00e9nements, des informations bas\u00e9es sur les donn\u00e9es et une biblioth\u00e8que d\u2019automatisations. En tirant parti des mod\u00e8les et des outils de segmentation disponibles, TM1 Engagement aide \u00e0 rationaliser toutes les communications par courriel de Peach Bowl, Inc., des renouvellements aux informations importantes sur la semaine du match.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;Nous utilisons TM1 Engagement pour communiquer avec nos fans pour vraiment tout ce que nous avons en cours. Cela a \u00e9t\u00e9 formidable pour nous. Tout ce qui est une offre par courriel \u00e0 notre base de donn\u00e9es, nous cr\u00e9ons un engagement et l\u2019envoyons.&nbsp;\u00bb<\/p>\n<cite>Mike Gilbert, directeur de la billetterie, Peach Bowl, Inc.<\/cite><\/blockquote>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/business.ticketmaster.com\/wp-content\/uploads\/2023\/11\/image.jpeg\" alt=\"This image has an empty alt attribute; its file name is Engagement-Image-2-1024x576.jpg\" class=\"wp-image-54461\"\/><figcaption class=\"wp-element-caption\"><em>Exemples de Peach Bowl, Inc. tirant parti de la puissance de TM1 Engagement pour communiquer avec les fans. Sur la photo de gauche&nbsp;: Instructions du Chick-fil-A Peach Bowl sur la fa\u00e7on de renouveler les billets par l\u2019interm\u00e9diaire d\u2019Account Manager. Sur la photo \u00e0 droite&nbsp;: Instructions d\u2019Aflac Kickoff Game sur la fa\u00e7on d\u2019acc\u00e9der aux billets num\u00e9riques le jour du match au Mercedes-Benz Stadium.<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tirer parti d\u2019un vaste r\u00e9seau de partenaires<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Gr\u00e2ce au <a href=\"https:\/\/business.ticketmaster.com\/nexus-partners\/\">programme de partenariat Nexus<\/a> de Ticketmaster, Peach Bowl, Inc. a acc\u00e8s \u00e0 plus de 95 partenaires technologiques certifi\u00e9s, y compris FEVO, une plateforme innovante de commerce \u00e9lectronique sur r\u00e9seaux sociaux qui facilite la vente de billets de groupe et les rabais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Peach Bowl, Inc. collabore avec FEVO en tirant parti de l\u2019int\u00e9gration transparente de la plateforme avec Ticketmaster.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gr\u00e2ce \u00e0 cette int\u00e9gration, Peach Bowl, Inc. a utilis\u00e9 FEVO pour suivre et g\u00e9rer une liste d\u2019attente pay\u00e9e pour le Chick-fil-A Peach Bowl, une initiative qui recueille des fonds pour leur Fondation de recherche sur le cancer infantile. FEVO permet \u00e9galement l\u2019entr\u00e9e aux \u00e9v\u00e9nements d\u2019admission g\u00e9n\u00e9rale organis\u00e9s par Peach Bowl, Inc. dans les installations entourant le Stade Mercedes-Benz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00c9lever les normes gr\u00e2ce \u00e0 un \u00e9tat d\u2019esprit novateur<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En adoptant l\u2019innovation, en donnant la priorit\u00e9 \u00e0 l\u2019exp\u00e9rience des fans et en favorisant les collaborations strat\u00e9giques, Peach Bowl, Inc. a \u00e9lev\u00e9 les normes d\u2019excellence du football universitaire. Apr\u00e8s treize ans de collaboration, Gilbert estime que travailler avec Ticketmaster permet \u00e0 Peach Bowl, Inc. de prendre des d\u00e9cisions audacieuses et de garder une longueur d\u2019avance, solidifiant leur position en tant qu\u2019h\u00f4te de premier plan pour les plus grands matchs du football universitaire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous souhaitez en savoir plus sur nos services? Veuillez contacter votre repr\u00e9sentant Ticketmaster ou <a href=\"https:\/\/business.ticketmaster.com\/fr\/nous-contacter\/\">nous contacter<\/a>.<a href=\"https:\/\/business.ticketmaster.com\/contact\/\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour plus d\u2019informations sur la fa\u00e7on dont Ticketmaster aide les clients de l\u2019athl\u00e9tisme coll\u00e9gial \u00e0 maximiser la valeur, visitez <a href=\"https:\/\/business.ticketmaster.com\/college\/\">ticketmastercollege.com<\/a>.<a href=\"https:\/\/business.ticketmaster.com\/college\/\"><\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Chaque ann\u00e9e, Peach Bowl, Inc. attire l\u2019attention nationale sur le Mercedes-Benz Stadium d\u2019Atlanta, en G\u00e9orgie, qui accueille certains des plus grands matchs de football universitaire de la saison. Des mois de planification vont dans ces \u00e9v\u00e9nements \u00e0 grande \u00e9chelle pour assurer une exp\u00e9rience transparente pour les fans le jour du match.&nbsp; Mike Gilbert, directeur de [&hellip;]<\/p>\n","protected":false},"author":79,"featured_media":53308,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"57159,57143,57060","_relevanssi_noindex_reason":"","footnotes":"[]"},"admin-category":[],"content-type":[],"solution":[],"segment":[],"venue":[],"topic":[],"class_list":["post-53307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-solutions-daffaires","category-soutien-en-permanence","category-temoignages-des-clients","tag-ticketmaster"],"acf":[],"_links":{"self":[{"href":"https:\/\/business.ticketmaster.com\/fr\/wp-json\/wp\/v2\/posts\/53307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/business.ticketmaster.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/business.ticketmaster.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/business.ticketmaster.com\/fr\/wp-json\/wp\/v2\/users\/79"}],"replies":[{"embeddable":true,"href":"https:\/\/business.ticketmaster.com\/fr\/wp-json\/wp\/v2\/comments?post=53307"}],"version-history":[{"count":0,"href":"https:\/\/business.ticketmaster.com\/fr\/wp-json\/wp\/v2\/posts\/53307\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/business.ticketmaster.com\/fr\/wp-json\/wp\/v2\/media\/53308"}],"wp:attachment":[{"href":"https:\/\/business.ticketmaster.com\/fr\/wp-json\/wp\/v2\/media?parent=53307"}],"wp:term":[{"taxonomy":"admin-category","embeddable":true,"href":"https:\/\/business.ticketmaster.com\/fr\/wp-json\/wp\/v2\/admin-category?post=53307"},{"taxonomy":"content-type","embeddable":true,"href":"https:\/\/business.ticketmaster.com\/fr\/wp-json\/wp\/v2\/content-type?post=53307"},{"taxonomy":"solution","embeddable":true,"href":"https:\/\/business.ticketmaster.com\/fr\/wp-json\/wp\/v2\/solution?post=53307"},{"taxonomy":"segment","embeddable":true,"href":"https:\/\/business.ticketmaster.com\/fr\/wp-json\/wp\/v2\/segment?post=53307"},{"taxonomy":"venue","embeddable":true,"href":"https:\/\/business.ticketmaster.com\/fr\/wp-json\/wp\/v2\/venue?post=53307"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/business.ticketmaster.com\/fr\/wp-json\/wp\/v2\/topic?post=53307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}